{"id":2982,"date":"2026-03-26T16:26:48","date_gmt":"2026-03-26T16:26:48","guid":{"rendered":"https:\/\/vinvej.dk\/kelleris-vingaard\/"},"modified":"2026-03-26T16:35:30","modified_gmt":"2026-03-26T16:35:30","slug":"kelleris-vingaard","status":"publish","type":"post","link":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/","title":{"rendered":"Kelleris Vingaard"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2982\" class=\"elementor elementor-2982 elementor-2974\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43645cb8 e-flex e-con-boxed e-con e-parent\" data-id=\"43645cb8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6607f18b e-con-full e-flex e-con e-child\" data-id=\"6607f18b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-284c5b26 elementor-widget elementor-widget-heading\" data-id=\"284c5b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kelleris Vingaard<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c4366e elementor-widget elementor-widget-post-info\" data-id=\"74c4366e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-7bc3993 elementor-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-globe\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M336.5 160C322 70.7 287.8 8 248 8s-74 62.7-88.5 152h177zM152 256c0 22.2 1.2 43.5 3.3 64h185.3c2.1-20.5 3.3-41.8 3.3-64s-1.2-43.5-3.3-64H155.3c-2.1 20.5-3.3 41.8-3.3 64zm324.7-96c-28.6-67.9-86.5-120.4-158-141.6 24.4 33.8 41.2 84.7 50 141.6h108zM177.2 18.4C105.8 39.6 47.8 92.1 19.3 160h108c8.7-56.9 25.5-107.8 49.9-141.6zM487.4 192H372.7c2.1 21 3.3 42.5 3.3 64s-1.2 43-3.3 64h114.6c5.5-20.5 8.6-41.8 8.6-64s-3.1-43.5-8.5-64zM120 256c0-21.5 1.2-43 3.3-64H8.6C3.2 212.5 0 233.8 0 256s3.2 43.5 8.6 64h114.6c-2-21-3.2-42.5-3.2-64zm39.5 96c14.5 89.3 48.7 152 88.5 152s74-62.7 88.5-152h-177zm159.3 141.6c71.4-21.2 129.4-73.7 158-141.6h-108c-8.8 56.9-25.6 107.8-50 141.6zM19.3 352c28.6 67.9 86.5 120.4 158 141.6-24.4-33.8-41.2-84.7-50-141.6h-108z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Sj\u00e6lland<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-f4aef46 elementor-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Tour<\/span>, <span class=\"elementor-post-info__terms-list-item\">Weinherstellung aus Trauben<\/span>, <span class=\"elementor-post-info__terms-list-item\">Weinprobe<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b2281ee e-con-full e-flex e-con e-child\" data-id=\"5b2281ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1da3da elementor-widget elementor-widget-text-editor\" data-id=\"2b1da3da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Web: <a href=\"https:\/\/www.kellerisvingaard.dk\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.kellerisvingaard.dk&amp;source=gmail&amp;ust=1774605145643000&amp;usg=AOvVaw1l5ch_grQxqjy-pzv6gfPy\">www.kellerisvingaard.dk<\/a><br>Mail: <a href=\"mailto:shj@kellerisvingaard.dk\" target=\"_blank\" rel=\"noopener\">shj@kellerisvingaard.dk<br>Email: shj@kellerisvingaard.dk<\/a> Tel: <a id=\"link_text-35-225\" class=\"ct-link-text atomic-footer-7-link\" href=\"tel:+4522463930\" target=\"_self\">+45 22463930<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c220d84 e-con-full e-flex e-con e-child\" data-id=\"2c220d84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-44871fb3 e-con-full e-flex e-con e-child\" data-id=\"44871fb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a34e5f elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"4a34e5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.instagram.com\/kellerisvingaard\/\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2273e6fd e-flex e-con-boxed e-con e-parent\" data-id=\"2273e6fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-45fe4b30 e-con-full e-flex e-con e-child\" data-id=\"45fe4b30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c679eaf elementor-widget elementor-widget-image\" data-id=\"2c679eaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard-1024x683.jpg\" class=\"attachment-large size-large wp-image-2984\" alt=\"Kelleris Vingaard\" srcset=\"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard-1024x683.jpg 1024w, https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard-300x200.jpg 300w, https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard-768x512.jpg 768w, https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14d78da9 e-con-full e-flex e-con e-child\" data-id=\"14d78da9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d4a9d13 elementor-widget elementor-widget-text-editor\" data-id=\"1d4a9d13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Kelleris Vingaard liegt in Nordseeland in der N\u00e4he der \u00d6resundk\u00fcste und des Louisiana-Museums in dem sch\u00f6nen Naturschutzgebiet Kelleris-kilen.<br>Das Weingut wurde 2001 gegr\u00fcndet und ist im Besitz von Susanne und S\u00f8ren Hartvig Jensen, die Pioniere der d\u00e4nischen Weinzucht sind. Eine Fl\u00e4che von 1,3 Hektar wurde mit etwa 4200 Rebst\u00f6cken bepflanzt, haupts\u00e4chlich mit den Sorten Rondo und Solaris. Im Jahr 2007 baute das Weingut seine eigene unterirdische Kellerei, in der alle Weinbereitungsprozesse stattfinden. Die UTOPIA-Weine des Weinguts werden mit Leidenschaft und einem starken Fokus auf Qualit\u00e4t und traditionelle Handwerkskunst hergestellt. Die Reben werden w\u00e4hrend der Vegetationsperiode intensiv getrimmt und beschnitten. Die Trauben werden von Hand gepfl\u00fcckt und sortiert, um sicherzustellen, dass nur die besten Fr\u00fcchte verwendet werden. Kelleris Weingut stellt Wei\u00dfwein, Sekt, Rotwein und Lik\u00f6rwein her. Der Schaumwein Utopia Ren\u00e9e wird nach der &#8222;Champagner&#8220;-Methode mit zweiter G\u00e4rung in der Flasche hergestellt. Der gespritete Wein Utopia BullsEye wird wie ein Portwein aus sehr reifen Trauben hergestellt, teilweise vergoren und mit dem kellereieigenen Weindestillat versetzt. Die Rotweine werden alle in F\u00e4ssern gereift, vorzugsweise in franz\u00f6sischen, amerikanischen und ungarischen Barriques.<br>Im Laufe der Jahre haben die Utopia-Weine mehrere Medaillen bei verschiedenen Weinmessen und Wettbewerben gewonnen.<br>Es ist m\u00f6glich, Kelleris Vingaard nach vorheriger Vereinbarung zu besuchen. Es werden F\u00fchrungen durch Feld und Keller sowie Weinverkostungen organisiert. Weitere Informationen finden Sie auf der Website des Weinguts <a href=\"http:\/\/www.kellerisvingaard.dk\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.kellerisvingaard.dk&amp;source=gmail&amp;ust=1774605145643000&amp;usg=AOvVaw1l5ch_grQxqjy-pzv6gfPy\">www.kellerisvingaard.dk<\/a>           <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5430b4 e-flex e-con-boxed e-con e-parent\" data-id=\"5430b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5190a137 e-con-full e-flex e-con e-child\" data-id=\"5190a137\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2eeae525 elementor-widget elementor-widget-spacer\" data-id=\"2eeae525\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-721a6184 elementor-widget elementor-widget-google_maps\" data-id=\"721a6184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Kellerisvej%2078%2C%203490%20Kvistg%C3%A5rd&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Kellerisvej 78, 3490 Kvistg\u00e5rd\"\n\t\t\t\t\taria-label=\"Kellerisvej 78, 3490 Kvistg\u00e5rd\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b13d603 e-flex e-con-boxed e-con e-parent\" data-id=\"6b13d603\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-591412d1 elementor-widget elementor-widget-spacer\" data-id=\"591412d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Kelleris Vingaard liegt in Nordseeland in der N\u00e4he der \u00d6resundk\u00fcste und des Louisiana-Museums in dem sch\u00f6nen Naturschutzgebiet Kelleris-kilen.<br \/>\nDas Weingut wurde 2001 gegr\u00fcndet und ist im Besitz von Susanne und S\u00f8ren Hartvig Jensen, die Pioniere der d\u00e4nischen Weinzucht sind. Eine Fl\u00e4che von 1,3 Hektar wurde mit etwa 4200 Rebst\u00f6cken bepflanzt, haupts\u00e4chlich mit den Sorten Rondo und Solaris. Das Weingut verf\u00fcgt \u00fcber einen eigenen unterirdischen Weinkeller, in dem alle Prozesse der Weinherstellung stattfinden. Die UTOPIA-Weine des Weinguts werden mit Leidenschaft und Fokus auf Qualit\u00e4t und traditionelle Handwerkskunst hergestellt. Kelleris Winery produziert Wei\u00dfwein, Schaumwein, Rotwein und Lik\u00f6rwein.<br \/>\nEs ist m\u00f6glich, Kelleris Winery nach vorheriger Absprache zu besuchen. Weitere Informationen finden Sie auf der Website des Weinguts www.kellerisvingaard.dk     <\/p>\n","protected":false},"author":1,"featured_media":2984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"iawp_total_views":2,"footnotes":""},"categories":[123],"tags":[109,105,110],"post_folder":[127],"class_list":["post-2982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sjaelland","tag-tour","tag-weinherstellung-aus-trauben","tag-weinprobe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kelleris Vingaard - Vinvej.dk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kelleris Vingaard - Vinvej.dk\" \/>\n<meta property=\"og:description\" content=\"Kelleris Vingaard liegt in Nordseeland in der N\u00e4he der \u00d6resundk\u00fcste und des Louisiana-Museums in dem sch\u00f6nen Naturschutzgebiet Kelleris-kilen. Das Weingut wurde 2001 gegr\u00fcndet und ist im Besitz von Susanne und S\u00f8ren Hartvig Jensen, die Pioniere der d\u00e4nischen Weinzucht sind. Eine Fl\u00e4che von 1,3 Hektar wurde mit etwa 4200 Rebst\u00f6cken bepflanzt, haupts\u00e4chlich mit den Sorten Rondo und Solaris. Das Weingut verf\u00fcgt \u00fcber einen eigenen unterirdischen Weinkeller, in dem alle Prozesse der Weinherstellung stattfinden. Die UTOPIA-Weine des Weinguts werden mit Leidenschaft und Fokus auf Qualit\u00e4t und traditionelle Handwerkskunst hergestellt. Kelleris Winery produziert Wei\u00dfwein, Schaumwein, Rotwein und Lik\u00f6rwein. Es ist m\u00f6glich, Kelleris Winery nach vorheriger Absprache zu besuchen. Weitere Informationen finden Sie auf der Website des Weinguts www.kellerisvingaard.dk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinvej.dk\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T16:26:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T16:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"kc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/\"},\"author\":{\"name\":\"kc\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#\\\/schema\\\/person\\\/86114f751a75142c6badc27f9a336cb8\"},\"headline\":\"Kelleris Vingaard\",\"datePublished\":\"2026-03-26T16:26:48+00:00\",\"dateModified\":\"2026-03-26T16:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vinvej.dk\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Kelleris-Vingaard.jpg\",\"keywords\":[\"Tour\",\"Weinherstellung aus Trauben\",\"Weinprobe\"],\"articleSection\":[\"Sj\u00e6lland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/\",\"url\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/\",\"name\":\"Kelleris Vingaard - Vinvej.dk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vinvej.dk\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Kelleris-Vingaard.jpg\",\"datePublished\":\"2026-03-26T16:26:48+00:00\",\"dateModified\":\"2026-03-26T16:35:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vinvej.dk\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Kelleris-Vingaard.jpg\",\"contentUrl\":\"https:\\\/\\\/vinvej.dk\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Kelleris-Vingaard.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Kelleris Vingaard\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/kelleris-vingaard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nicht kategorisiert\",\"item\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/category\\\/nicht-kategorisiert\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kelleris Vingaard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/\",\"name\":\"Vinvej.dk\",\"description\":\"GUIDE TIL DANSKE VINE OG VING\u00c5RDE\",\"publisher\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#organization\",\"name\":\"Vinvej.dk\",\"url\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vinvej.dk\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo_200px.jpg\",\"contentUrl\":\"https:\\\/\\\/vinvej.dk\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo_200px.jpg\",\"width\":200,\"height\":223,\"caption\":\"Vinvej.dk\"},\"image\":{\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/#\\\/schema\\\/person\\\/86114f751a75142c6badc27f9a336cb8\",\"name\":\"kc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19443eeb4c619c65dd97bb0223224f6b449e127ae106de064e0b03b70efe3b66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19443eeb4c619c65dd97bb0223224f6b449e127ae106de064e0b03b70efe3b66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19443eeb4c619c65dd97bb0223224f6b449e127ae106de064e0b03b70efe3b66?s=96&d=mm&r=g\",\"caption\":\"kc\"},\"sameAs\":[\"https:\\\/\\\/vinvej.dk\"],\"url\":\"https:\\\/\\\/vinvej.dk\\\/de\\\/author\\\/kc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kelleris Vingaard - Vinvej.dk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/","og_locale":"de_DE","og_type":"article","og_title":"Kelleris Vingaard - Vinvej.dk","og_description":"Kelleris Vingaard liegt in Nordseeland in der N\u00e4he der \u00d6resundk\u00fcste und des Louisiana-Museums in dem sch\u00f6nen Naturschutzgebiet Kelleris-kilen. Das Weingut wurde 2001 gegr\u00fcndet und ist im Besitz von Susanne und S\u00f8ren Hartvig Jensen, die Pioniere der d\u00e4nischen Weinzucht sind. Eine Fl\u00e4che von 1,3 Hektar wurde mit etwa 4200 Rebst\u00f6cken bepflanzt, haupts\u00e4chlich mit den Sorten Rondo und Solaris. Das Weingut verf\u00fcgt \u00fcber einen eigenen unterirdischen Weinkeller, in dem alle Prozesse der Weinherstellung stattfinden. Die UTOPIA-Weine des Weinguts werden mit Leidenschaft und Fokus auf Qualit\u00e4t und traditionelle Handwerkskunst hergestellt. Kelleris Winery produziert Wei\u00dfwein, Schaumwein, Rotwein und Lik\u00f6rwein. Es ist m\u00f6glich, Kelleris Winery nach vorheriger Absprache zu besuchen. Weitere Informationen finden Sie auf der Website des Weinguts www.kellerisvingaard.dk","og_url":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/","og_site_name":"Vinvej.dk","article_published_time":"2026-03-26T16:26:48+00:00","article_modified_time":"2026-03-26T16:35:30+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard.jpg","type":"image\/jpeg"}],"author":"kc","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"kc","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#article","isPartOf":{"@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/"},"author":{"name":"kc","@id":"https:\/\/vinvej.dk\/de\/#\/schema\/person\/86114f751a75142c6badc27f9a336cb8"},"headline":"Kelleris Vingaard","datePublished":"2026-03-26T16:26:48+00:00","dateModified":"2026-03-26T16:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/vinvej.dk\/de\/#organization"},"image":{"@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#primaryimage"},"thumbnailUrl":"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard.jpg","keywords":["Tour","Weinherstellung aus Trauben","Weinprobe"],"articleSection":["Sj\u00e6lland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/","url":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/","name":"Kelleris Vingaard - Vinvej.dk","isPartOf":{"@id":"https:\/\/vinvej.dk\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#primaryimage"},"image":{"@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#primaryimage"},"thumbnailUrl":"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard.jpg","datePublished":"2026-03-26T16:26:48+00:00","dateModified":"2026-03-26T16:35:30+00:00","breadcrumb":{"@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vinvej.dk\/de\/kelleris-vingaard\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#primaryimage","url":"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard.jpg","contentUrl":"https:\/\/vinvej.dk\/wp-content\/uploads\/2026\/03\/Kelleris-Vingaard.jpg","width":1200,"height":800,"caption":"Kelleris Vingaard"},{"@type":"BreadcrumbList","@id":"https:\/\/vinvej.dk\/de\/kelleris-vingaard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/vinvej.dk\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Nicht kategorisiert","item":"https:\/\/vinvej.dk\/de\/category\/nicht-kategorisiert\/"},{"@type":"ListItem","position":3,"name":"Kelleris Vingaard"}]},{"@type":"WebSite","@id":"https:\/\/vinvej.dk\/de\/#website","url":"https:\/\/vinvej.dk\/de\/","name":"Vinvej.dk","description":"GUIDE TIL DANSKE VINE OG VING\u00c5RDE","publisher":{"@id":"https:\/\/vinvej.dk\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vinvej.dk\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/vinvej.dk\/de\/#organization","name":"Vinvej.dk","url":"https:\/\/vinvej.dk\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vinvej.dk\/de\/#\/schema\/logo\/image\/","url":"https:\/\/vinvej.dk\/wp-content\/uploads\/2025\/10\/logo_200px.jpg","contentUrl":"https:\/\/vinvej.dk\/wp-content\/uploads\/2025\/10\/logo_200px.jpg","width":200,"height":223,"caption":"Vinvej.dk"},"image":{"@id":"https:\/\/vinvej.dk\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vinvej.dk\/de\/#\/schema\/person\/86114f751a75142c6badc27f9a336cb8","name":"kc","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/19443eeb4c619c65dd97bb0223224f6b449e127ae106de064e0b03b70efe3b66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19443eeb4c619c65dd97bb0223224f6b449e127ae106de064e0b03b70efe3b66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19443eeb4c619c65dd97bb0223224f6b449e127ae106de064e0b03b70efe3b66?s=96&d=mm&r=g","caption":"kc"},"sameAs":["https:\/\/vinvej.dk"],"url":"https:\/\/vinvej.dk\/de\/author\/kc\/"}]}},"_links":{"self":[{"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/posts\/2982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/comments?post=2982"}],"version-history":[{"count":1,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/posts\/2982\/revisions"}],"predecessor-version":[{"id":2985,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/posts\/2982\/revisions\/2985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/media\/2984"}],"wp:attachment":[{"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/media?parent=2982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/categories?post=2982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/tags?post=2982"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/vinvej.dk\/de\/wp-json\/wp\/v2\/post_folder?post=2982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}